{"id":277,"count":0,"description":"D\u00e9couvrez des parcs d'exercice et des barri\u00e8res de haute qualit\u00e9 pour vos animaux de compagnie. Nos produits durables et s\u00e9curis\u00e9s garantissent un environnement s\u00fbr et confortable \u00e0 vos amis \u00e0 fourrure. Parfait pour l'int\u00e9rieur et l'ext\u00e9rieur.","link":"https:\/\/flawless.pet\/fr\/product-category\/dogs\/kennels-gates-doors\/exercise-pens-gates\/","name":"Cages d'exercice et barri\u00e8res","slug":"stylos-dexercice-barrieres","taxonomy":"product_cat","parent":275,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/product_cat\/277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/product_cat\/275"}],"wp:post_type":[{"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/product?product_cat=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}