{"id":288,"count":0,"description":"Aliment humide de premi\u00e8re qualit\u00e9 pour animaux de compagnie, riche en nutriments essentiels. Parfait pour les chats et les chiens. Des recettes d\u00e9licieuses et nutritives pour garder vos animaux en bonne sant\u00e9 et heureux.","link":"https:\/\/flawless.pet\/fr\/product-category\/cats\/cat-food-center\/wet-food-cat-food-center\/","name":"Aliments humides","slug":"nourriture-humide-centre-de-nourriture-pour-chats","taxonomy":"product_cat","parent":286,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/product_cat\/288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/product_cat\/286"}],"wp:post_type":[{"href":"https:\/\/flawless.pet\/fr\/wp-json\/wp\/v2\/product?product_cat=288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}